{"id":4965,"date":"2025-11-04T12:05:12","date_gmt":"2025-11-04T12:05:12","guid":{"rendered":"https:\/\/swisstreasures.ch\/?post_type=product&#038;p=4965"},"modified":"2026-06-15T12:02:26","modified_gmt":"2026-06-15T12:02:26","slug":"patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name","status":"publish","type":"product","link":"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/","title":{"rendered":"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>A rare and splendid Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed stainless steel wristwatch. NOS Full set Anonymous name<\/p>\n<p><strong>Reference:<\/strong> 5711\/1A-010<br \/>\n<strong>Model:<\/strong> Nautilus<br \/>\n<strong>Material:<\/strong> Stainless steel<br \/>\n<strong>Calibre:<\/strong> Automatic, cal. 324 S C, 29 jewels<br \/>\n<strong>Bracelet\/Strap:<\/strong> Stainless steel Patek Philippe bracelet<br \/>\n<strong>Clasp\/Buckle:<\/strong> Stainless steel Patek Philippe deployant clasp<br \/>\n<strong>Dial:<\/strong> Blue<br \/>\n<strong>Signed:<\/strong> Case, dial, movement, bracelet and clasp signed<br \/>\n<strong>Diameter:<\/strong> 40 mm<br \/>\n<strong>Year:<\/strong> 2017<br \/>\n<strong>Accessories:<\/strong> Accompanied by Patek Philippe Certificate of Origin with Anonymous name, instruction manual, product literature, outer packaging and fitted presentation box.<br \/>\n<strong>Condition:<\/strong> NOS Full set<br \/>\nThe watch is kept in our safe from 2017<\/p>\n<p>ID SWT: 77026161<\/p>\n","protected":false},"featured_media":4966,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[27],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name - SWISSTREASURES SA<\/title>\n<meta name=\"description\" content=\"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name - SWISSTREASURES SA\" \/>\n<meta property=\"og:description\" content=\"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/\" \/>\n<meta property=\"og:site_name\" content=\"SWISSTREASURES \u2013 Acheter et vendre des montres \u00e0 Gen\u00e8ve\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T12:02:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swisstreasures.ch\/wp-content\/uploads\/2025\/11\/IMG_2266-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1512\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/\",\"url\":\"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/\",\"name\":\"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name - SWISSTREASURES SA\",\"isPartOf\":{\"@id\":\"https:\/\/swisstreasures.ch\/#website\"},\"datePublished\":\"2025-11-04T12:05:12+00:00\",\"dateModified\":\"2026-06-15T12:02:26+00:00\",\"description\":\"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name\",\"breadcrumb\":{\"@id\":\"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/swisstreasures.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/swisstreasures.ch\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swisstreasures.ch\/#website\",\"url\":\"https:\/\/swisstreasures.ch\/\",\"name\":\"SWISSTREASURES \u2013 Acheter et vendre des montres \u00e0 Gen\u00e8ve\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/swisstreasures.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swisstreasures.ch\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/swisstreasures.ch\/#organization\",\"name\":\"SWISSTREASURES \u2013 Acheter et vendre des montres \u00e0 Gen\u00e8ve\",\"url\":\"https:\/\/swisstreasures.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/swisstreasures.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/swisstreasures.ch\/wp-content\/uploads\/2021\/02\/LOGOSITEIDENTITY-1.png\",\"contentUrl\":\"https:\/\/swisstreasures.ch\/wp-content\/uploads\/2021\/02\/LOGOSITEIDENTITY-1.png\",\"width\":974,\"height\":133,\"caption\":\"SWISSTREASURES \u2013 Acheter et vendre des montres \u00e0 Gen\u00e8ve\"},\"image\":{\"@id\":\"https:\/\/swisstreasures.ch\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name - SWISSTREASURES SA","description":"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/","og_locale":"en_US","og_type":"article","og_title":"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name - SWISSTREASURES SA","og_description":"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name","og_url":"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/","og_site_name":"SWISSTREASURES \u2013 Acheter et vendre des montres \u00e0 Gen\u00e8ve","article_modified_time":"2026-06-15T12:02:26+00:00","og_image":[{"width":1512,"height":1512,"url":"https:\/\/swisstreasures.ch\/wp-content\/uploads\/2025\/11\/IMG_2266-min.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/","url":"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/","name":"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name - SWISSTREASURES SA","isPartOf":{"@id":"https:\/\/swisstreasures.ch\/#website"},"datePublished":"2025-11-04T12:05:12+00:00","dateModified":"2026-06-15T12:02:26+00:00","description":"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name","breadcrumb":{"@id":"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swisstreasures.ch\/index.php\/product\/patek-philippe-nautilus-5711-1a-010-double-factory-sealed-nos-anonymous-name\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swisstreasures.ch\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/swisstreasures.ch\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Patek Philippe Nautilus 5711\/1A-010 Double Factory Sealed NOS Anonymous name"}]},{"@type":"WebSite","@id":"https:\/\/swisstreasures.ch\/#website","url":"https:\/\/swisstreasures.ch\/","name":"SWISSTREASURES \u2013 Acheter et vendre des montres \u00e0 Gen\u00e8ve","description":"","publisher":{"@id":"https:\/\/swisstreasures.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swisstreasures.ch\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/swisstreasures.ch\/#organization","name":"SWISSTREASURES \u2013 Acheter et vendre des montres \u00e0 Gen\u00e8ve","url":"https:\/\/swisstreasures.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/swisstreasures.ch\/#\/schema\/logo\/image\/","url":"https:\/\/swisstreasures.ch\/wp-content\/uploads\/2021\/02\/LOGOSITEIDENTITY-1.png","contentUrl":"https:\/\/swisstreasures.ch\/wp-content\/uploads\/2021\/02\/LOGOSITEIDENTITY-1.png","width":974,"height":133,"caption":"SWISSTREASURES \u2013 Acheter et vendre des montres \u00e0 Gen\u00e8ve"},"image":{"@id":"https:\/\/swisstreasures.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/swisstreasures.ch\/index.php\/wp-json\/wp\/v2\/product\/4965"}],"collection":[{"href":"https:\/\/swisstreasures.ch\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/swisstreasures.ch\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/swisstreasures.ch\/index.php\/wp-json\/wp\/v2\/comments?post=4965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swisstreasures.ch\/index.php\/wp-json\/wp\/v2\/media\/4966"}],"wp:attachment":[{"href":"https:\/\/swisstreasures.ch\/index.php\/wp-json\/wp\/v2\/media?parent=4965"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/swisstreasures.ch\/index.php\/wp-json\/wp\/v2\/product_cat?post=4965"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/swisstreasures.ch\/index.php\/wp-json\/wp\/v2\/product_tag?post=4965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}